{"id":1344,"date":"2021-08-10T18:46:18","date_gmt":"2021-08-10T15:46:18","guid":{"rendered":"https:\/\/www.alhayahtech.com\/?page_id=1344"},"modified":"2021-08-10T22:26:39","modified_gmt":"2021-08-10T19:26:39","slug":"checkout-twit-2-5k-130d","status":"publish","type":"page","link":"https:\/\/www.mfhgpt.com\/en\/checkout-twit-2-5k-130d\/","title":{"rendered":"Checkout &#8211; twit-2.5K-130d"},"content":{"rendered":"\r\n<div class=\"row\"  id=\"row-967869870\">\r\n\r\n\n\t<div id=\"col-1288734704\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_861803567\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"615\" height=\"400\" src=\"https:\/\/www.mfhgpt.com\/wp-content\/uploads\/2021\/08\/2411-copy-min-615x400.png\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mfhgpt.com\/wp-content\/uploads\/2021\/08\/2411-copy-min-615x400.png 615w, https:\/\/www.mfhgpt.com\/wp-content\/uploads\/2021\/08\/2411-copy-min-1231x800.png 1231w, https:\/\/www.mfhgpt.com\/wp-content\/uploads\/2021\/08\/2411-copy-min-768x499.png 768w, https:\/\/www.mfhgpt.com\/wp-content\/uploads\/2021\/08\/2411-copy-min-1536x998.png 1536w, https:\/\/www.mfhgpt.com\/wp-content\/uploads\/2021\/08\/2411-copy-min.png 2000w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_861803567 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1885751527\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Checkout (twit-2.5K-130d)<\/span><b><\/b><\/h3><\/div>\r\n\r\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f1519-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1344#wpcf7-f1519-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1519\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1519-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:1519,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false}}\" \/>\n<\/div>\n<div class=\"form-flat\">\n<label>Your Twitter Account :<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap username\"><input type=\"text\" name=\"username\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><br \/>\n<label>Your E-mail:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap email\"><input type=\"email\" name=\"email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><br \/>\n<label>Mobile:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap phone\"><input type=\"tel\" name=\"phone-cf7it-national\" value=\"\" class=\"wpcf7-form-control wpcf7-intl-tel wpcf7-intl_tel wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" data-initialcountry=\"ae\" \/><input type=\"hidden\" name=\"phone\" class=\"wpcf7-intl-tel-full\" \/><input type=\"hidden\" name=\"phone-cf7it-country-name\" class=\"wpcf7-intl-tel-country-name\" \/><input type=\"hidden\" name=\"phone-cf7it-country-code\" class=\"wpcf7-intl-tel-country-code\" \/><input type=\"hidden\" name=\"phone-cf7it-country-iso2\" class=\"wpcf7-intl-tel-country-iso2\" \/><\/span><br \/>\n<label><\/label><br \/>\n<input type=\"submit\" value=\"Continue to Pay\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<\/div>\n<\/form><\/div>\r\n\r\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/pages\/1344"}],"collection":[{"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/comments?post=1344"}],"version-history":[{"count":0,"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/pages\/1344\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mfhgpt.com\/en\/wp-json\/wp\/v2\/media?parent=1344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}